{"id":1859,"date":"2019-03-07T09:01:40","date_gmt":"2019-03-07T08:01:40","guid":{"rendered":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/"},"modified":"2024-12-16T10:48:11","modified_gmt":"2024-12-16T09:48:11","slug":"farine-de-fumaison-weber-hetre","status":"publish","type":"product","link":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/","title":{"rendered":"Sciure pour fumage Weber &#8211; H\u00eatre 0.5kg"},"content":{"rendered":"<p>Une envie de saumon fum\u00e9, de bacon maison ou peut-\u00eatre de tranches de filet de veau fum\u00e9 ? Plongez-vous dans l&rsquo;art du fumage \u00e0 froid en utilisant cette fine sciure de h\u00eatre en association avec le fumoir de fumage \u00e0 froid. La sciure se consumera lentement, jusqu&rsquo;\u00e0 10 heures, en donnant aux aliments un subtil go\u00fbt fum\u00e9.<\/p>\n<p>CARACT\u00c9RISTIQUES<\/p>\n<ul>\n<li>Convient pour le fumage \u00e0 froid de jambons, saucisses, poissons et fromages<\/li>\n<li>Temps de combustion 8-10 h<\/li>\n<li>Id\u00e9alement utilis\u00e9 avec le <a href=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/unite-de-fumaison-a-froid-weber\/\">fumoir pour fumage \u00e0 froid<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>17614<\/p>\n","protected":false},"featured_media":3677,"template":"","meta":[],"product_cat":[165],"product_tag":[84],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sciure pour fumage Weber - H\u00eatre 0.5kg - Grills et Saveurs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sciure pour fumage Weber - H\u00eatre 0.5kg - Grills et Saveurs\" \/>\n<meta property=\"og:description\" content=\"17614\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/\" \/>\n<meta property=\"og:site_name\" content=\"Grills et Saveurs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T09:48:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2019\/03\/17614-Sciure-pour-fumage-Weber-H\u00eatre-0.5kg-Smoking-Dust-Beech.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"950\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/\",\"name\":\"Grills et Saveurs\",\"description\":\"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2019\/03\/17614-Sciure-pour-fumage-Weber-H\u00eatre-0.5kg-Smoking-Dust-Beech.png\",\"contentUrl\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2019\/03\/17614-Sciure-pour-fumage-Weber-H\u00eatre-0.5kg-Smoking-Dust-Beech.png\",\"width\":1000,\"height\":950,\"caption\":\"17614 Sciure pour fumage Weber H\u00eatre 0.5kg Smoking Dust Beech\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/#webpage\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/\",\"name\":\"Sciure pour fumage Weber - H\u00eatre 0.5kg - Grills et Saveurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/#primaryimage\"},\"datePublished\":\"2019-03-07T08:01:40+00:00\",\"dateModified\":\"2024-12-16T09:48:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop \/ Boutique\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sciure pour fumage Weber &#8211; H\u00eatre 0.5kg\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sciure pour fumage Weber - H\u00eatre 0.5kg - Grills et Saveurs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/","og_locale":"fr_FR","og_type":"article","og_title":"Sciure pour fumage Weber - H\u00eatre 0.5kg - Grills et Saveurs","og_description":"17614","og_url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/","og_site_name":"Grills et Saveurs","article_modified_time":"2024-12-16T09:48:11+00:00","og_image":[{"width":1000,"height":950,"url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2019\/03\/17614-Sciure-pour-fumage-Weber-H\u00eatre-0.5kg-Smoking-Dust-Beech.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website","url":"https:\/\/www.grills-saveurs.ch\/fr\/","name":"Grills et Saveurs","description":"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2019\/03\/17614-Sciure-pour-fumage-Weber-H\u00eatre-0.5kg-Smoking-Dust-Beech.png","contentUrl":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2019\/03\/17614-Sciure-pour-fumage-Weber-H\u00eatre-0.5kg-Smoking-Dust-Beech.png","width":1000,"height":950,"caption":"17614 Sciure pour fumage Weber H\u00eatre 0.5kg Smoking Dust Beech"},{"@type":"WebPage","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/#webpage","url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/","name":"Sciure pour fumage Weber - H\u00eatre 0.5kg - Grills et Saveurs","isPartOf":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/#primaryimage"},"datePublished":"2019-03-07T08:01:40+00:00","dateModified":"2024-12-16T09:48:11+00:00","breadcrumb":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/farine-de-fumaison-weber-hetre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.grills-saveurs.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop \/ Boutique","item":"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Sciure pour fumage Weber &#8211; H\u00eatre 0.5kg"}]}]}},"_links":{"self":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product\/1859"}],"collection":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media\/3677"}],"wp:attachment":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media?parent=1859"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=1859"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=1859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}