{"id":5107,"date":"2020-03-30T10:14:59","date_gmt":"2020-03-30T08:14:59","guid":{"rendered":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/"},"modified":"2024-03-22T15:19:41","modified_gmt":"2024-03-22T14:19:41","slug":"protecteur-de-fonte-weber-200-ml","status":"publish","type":"product","link":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/","title":{"rendered":"Protecteur de fonte Weber 200 ml"},"content":{"rendered":"<p>Prot\u00e9gez toutes vos grilles et accessoires en fonte contre la rouille avec ce spray produisant une brume fine 100 % naturelle et efficace. Utilisez-le r\u00e9guli\u00e8rement pour un bon entretien de la fonte.<\/p>\n<p><strong>CARACT\u00c9RISTIQUES<\/strong><\/p>\n<ul>\n<li>Pas d&rsquo;ingr\u00e9dients dangereux<\/li>\n<li>Aucune alt\u00e9ration du go\u00fbt<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>17889<\/p>\n","protected":false},"featured_media":5185,"template":"","meta":[],"product_cat":[152,122],"product_tag":[84],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Protecteur de fonte Weber 200 ml - Grills et Saveurs<\/title>\n<meta name=\"description\" content=\"Prot\u00e9gez toutes vos grilles et accessoires en fonte contre la rouille avec ce spray produisant une brume fine 100 % naturelle et efficace. Utilisez-le ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protecteur de fonte Weber 200 ml - Grills et Saveurs\" \/>\n<meta property=\"og:description\" content=\"Prot\u00e9gez toutes vos grilles et accessoires en fonte contre la rouille avec ce spray produisant une brume fine 100 % naturelle et efficace. Utilisez-le ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Grills et Saveurs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-22T14:19:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2020\/03\/17889_protecteur_fonte_weber.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"950\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/\",\"name\":\"Grills et Saveurs\",\"description\":\"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2020\/03\/17889_protecteur_fonte_weber.png\",\"contentUrl\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2020\/03\/17889_protecteur_fonte_weber.png\",\"width\":1000,\"height\":950,\"caption\":\"Protecteur de fonte Weber 200 ml\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/#webpage\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/\",\"name\":\"Protecteur de fonte Weber 200 ml - Grills et Saveurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/#primaryimage\"},\"datePublished\":\"2020-03-30T08:14:59+00:00\",\"dateModified\":\"2024-03-22T14:19:41+00:00\",\"description\":\"Prot\u00e9gez toutes vos grilles et accessoires en fonte contre la rouille avec ce spray produisant une brume fine 100 % naturelle et efficace. Utilisez-le ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop \/ Boutique\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Protecteur de fonte Weber 200 ml\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protecteur de fonte Weber 200 ml - Grills et Saveurs","description":"Prot\u00e9gez toutes vos grilles et accessoires en fonte contre la rouille avec ce spray produisant une brume fine 100 % naturelle et efficace. Utilisez-le ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/","og_locale":"fr_FR","og_type":"article","og_title":"Protecteur de fonte Weber 200 ml - Grills et Saveurs","og_description":"Prot\u00e9gez toutes vos grilles et accessoires en fonte contre la rouille avec ce spray produisant une brume fine 100 % naturelle et efficace. Utilisez-le ...","og_url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/","og_site_name":"Grills et Saveurs","article_modified_time":"2024-03-22T14:19:41+00:00","og_image":[{"width":1000,"height":950,"url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2020\/03\/17889_protecteur_fonte_weber.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website","url":"https:\/\/www.grills-saveurs.ch\/fr\/","name":"Grills et Saveurs","description":"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2020\/03\/17889_protecteur_fonte_weber.png","contentUrl":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2020\/03\/17889_protecteur_fonte_weber.png","width":1000,"height":950,"caption":"Protecteur de fonte Weber 200 ml"},{"@type":"WebPage","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/#webpage","url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/","name":"Protecteur de fonte Weber 200 ml - Grills et Saveurs","isPartOf":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/#primaryimage"},"datePublished":"2020-03-30T08:14:59+00:00","dateModified":"2024-03-22T14:19:41+00:00","description":"Prot\u00e9gez toutes vos grilles et accessoires en fonte contre la rouille avec ce spray produisant une brume fine 100 % naturelle et efficace. Utilisez-le ...","breadcrumb":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/protecteur-de-fonte-weber-200-ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.grills-saveurs.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop \/ Boutique","item":"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Protecteur de fonte Weber 200 ml"}]}]}},"_links":{"self":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product\/5107"}],"collection":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media\/5185"}],"wp:attachment":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media?parent=5107"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=5107"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=5107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}