{"id":6992,"date":"2021-03-15T21:34:27","date_gmt":"2021-03-15T20:34:27","guid":{"rendered":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rtissoire-pour-barbecues-charbon-57-cm\/"},"modified":"2024-03-21T14:29:32","modified_gmt":"2024-03-21T13:29:32","slug":"rotissoire-pour-barbecues-charbon-57-cm","status":"publish","type":"product","link":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/","title":{"rendered":"R\u00f4tissoire pour barbecues charbon 57 cm"},"content":{"rendered":"<p>Accordez-vous un peu de temps libre \u00e0 la maison et pr\u00e9parez-vous pour une viande exceptionnelle cuite au barbecue. Enfilez le r\u00f4ti de porc, le poulet ou le gigot d&rsquo;agneau sur la broche de la r\u00f4tissoire, et laissez tourner sous le couvercle pendant que vous profitez d&rsquo;un bon moment en famille ou avec des amis. Vous pourrez bient\u00f4t servir de la viande tendre, non s\u00e8che et grill\u00e9e de mani\u00e8re bien uniforme.<\/p>\n<p>Compatible : Barbecues \u00e0 charbon Weber \u00d857 cm<\/p>\n<h5>Caract\u00e9ristiques<\/h5>\n<p>L&rsquo;ensemble comprend un anneau d&rsquo;extension, une broche, des fourches, un moteur et un adaptateur 220 v avec fiche \u00e0 3 broches.<br \/>\nPermet de tout cuire, des petits poulets aux grosses dindes enti\u00e8res.<\/p>\n<p>Dimensions du produit : 13.21cm h x 9.91cm l x 80.26cm p<br \/>\nDimensions du carton : 79.38cm h x 19.05cm l x 61.6cm p<br \/>\nConseils de nettoyage : laver l\u2019axe \u00e0 la main, seules les fourches passent au lave-vaisselle<\/p>\n","protected":false},"excerpt":{"rendered":"<p>7494<\/p>\n","protected":false},"featured_media":7170,"template":"","meta":[],"product_cat":[15,161],"product_tag":[84],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00f4tissoire pour barbecues charbon 57 cm - Grills et Saveurs<\/title>\n<meta name=\"description\" content=\"N\u2019allez pas plus loin que votre jardin pour d\u00e9guster un d\u00e9licieux poulet cuit \u00e0 la broche Weber et obtenir un poulet unique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00f4tissoire pour barbecues charbon 57 cm - Grills et Saveurs\" \/>\n<meta property=\"og:description\" content=\"N\u2019allez pas plus loin que votre jardin pour d\u00e9guster un d\u00e9licieux poulet cuit \u00e0 la broche Weber et obtenir un poulet unique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/\" \/>\n<meta property=\"og:site_name\" content=\"Grills et Saveurs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T13:29:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2021\/03\/7494.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"950\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/\",\"name\":\"Grills et Saveurs\",\"description\":\"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2021\/03\/7494.png\",\"contentUrl\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2021\/03\/7494.png\",\"width\":1000,\"height\":950,\"caption\":\"R\u00f4tissoire Weber \u00e0 charbon \u00f857 cm\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/#webpage\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/\",\"name\":\"R\u00f4tissoire pour barbecues charbon 57 cm - Grills et Saveurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/#primaryimage\"},\"datePublished\":\"2021-03-15T20:34:27+00:00\",\"dateModified\":\"2024-03-21T13:29:32+00:00\",\"description\":\"N\u2019allez pas plus loin que votre jardin pour d\u00e9guster un d\u00e9licieux poulet cuit \u00e0 la broche Weber et obtenir un poulet unique.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop \/ Boutique\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R\u00f4tissoire pour barbecues charbon 57 cm\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00f4tissoire pour barbecues charbon 57 cm - Grills et Saveurs","description":"N\u2019allez pas plus loin que votre jardin pour d\u00e9guster un d\u00e9licieux poulet cuit \u00e0 la broche Weber et obtenir un poulet unique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00f4tissoire pour barbecues charbon 57 cm - Grills et Saveurs","og_description":"N\u2019allez pas plus loin que votre jardin pour d\u00e9guster un d\u00e9licieux poulet cuit \u00e0 la broche Weber et obtenir un poulet unique.","og_url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/","og_site_name":"Grills et Saveurs","article_modified_time":"2024-03-21T13:29:32+00:00","og_image":[{"width":1000,"height":950,"url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2021\/03\/7494.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website","url":"https:\/\/www.grills-saveurs.ch\/fr\/","name":"Grills et Saveurs","description":"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2021\/03\/7494.png","contentUrl":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2021\/03\/7494.png","width":1000,"height":950,"caption":"R\u00f4tissoire Weber \u00e0 charbon \u00f857 cm"},{"@type":"WebPage","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/#webpage","url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/","name":"R\u00f4tissoire pour barbecues charbon 57 cm - Grills et Saveurs","isPartOf":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/#primaryimage"},"datePublished":"2021-03-15T20:34:27+00:00","dateModified":"2024-03-21T13:29:32+00:00","description":"N\u2019allez pas plus loin que votre jardin pour d\u00e9guster un d\u00e9licieux poulet cuit \u00e0 la broche Weber et obtenir un poulet unique.","breadcrumb":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/rotissoire-pour-barbecues-charbon-57-cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.grills-saveurs.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop \/ Boutique","item":"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"R\u00f4tissoire pour barbecues charbon 57 cm"}]}]}},"_links":{"self":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product\/6992"}],"collection":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media\/7170"}],"wp:attachment":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media?parent=6992"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=6992"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=6992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}