{"id":7787,"date":"2022-05-23T13:49:31","date_gmt":"2022-05-23T11:49:31","guid":{"rendered":"https:\/\/www.grills-saveurs.ch\/fr\/?post_type=product&#038;p=7787"},"modified":"2024-04-08T11:49:43","modified_gmt":"2024-04-08T09:49:43","slug":"grille-en-fonte-compact","status":"publish","type":"product","link":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/","title":{"rendered":"Grille En Fonte Compact"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7931,"template":"","meta":[],"product_cat":[229,230],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grille En Fonte Compact - Grills et Saveurs<\/title>\n<meta name=\"description\" content=\"Grille En Fonte Compact\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grille En Fonte Compact - Grills et Saveurs\" \/>\n<meta property=\"og:description\" content=\"Grille En Fonte Compact\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/\" \/>\n<meta property=\"og:site_name\" content=\"Grills et Saveurs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T09:49:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.12_Rost-aus-Gusseisen.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/\",\"name\":\"Grills et Saveurs\",\"description\":\"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.12_Rost-aus-Gusseisen.png\",\"contentUrl\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.12_Rost-aus-Gusseisen.png\",\"width\":1200,\"height\":1200},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/#webpage\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/\",\"name\":\"Grille En Fonte Compact - Grills et Saveurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/#primaryimage\"},\"datePublished\":\"2022-05-23T11:49:31+00:00\",\"dateModified\":\"2024-04-08T09:49:43+00:00\",\"description\":\"Grille En Fonte Compact\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop \/ Boutique\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grille En Fonte Compact\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grille En Fonte Compact - Grills et Saveurs","description":"Grille En Fonte Compact","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/","og_locale":"fr_FR","og_type":"article","og_title":"Grille En Fonte Compact - Grills et Saveurs","og_description":"Grille En Fonte Compact","og_url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/","og_site_name":"Grills et Saveurs","article_modified_time":"2024-04-08T09:49:43+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.12_Rost-aus-Gusseisen.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website","url":"https:\/\/www.grills-saveurs.ch\/fr\/","name":"Grills et Saveurs","description":"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.12_Rost-aus-Gusseisen.png","contentUrl":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.12_Rost-aus-Gusseisen.png","width":1200,"height":1200},{"@type":"WebPage","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/#webpage","url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/","name":"Grille En Fonte Compact - Grills et Saveurs","isPartOf":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/#primaryimage"},"datePublished":"2022-05-23T11:49:31+00:00","dateModified":"2024-04-08T09:49:43+00:00","description":"Grille En Fonte Compact","breadcrumb":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/grille-en-fonte-compact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.grills-saveurs.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop \/ Boutique","item":"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Grille En Fonte Compact"}]}]}},"_links":{"self":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product\/7787"}],"collection":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media\/7931"}],"wp:attachment":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media?parent=7787"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=7787"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=7787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}