{"id":7855,"date":"2022-05-23T14:25:42","date_gmt":"2022-05-23T12:25:42","guid":{"rendered":"https:\/\/www.grills-saveurs.ch\/fr\/?post_type=product&#038;p=7855"},"modified":"2024-04-08T11:49:36","modified_gmt":"2024-04-08T09:49:36","slug":"pierre-a-pizza-large","status":"publish","type":"product","link":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/","title":{"rendered":"Pierre \u00e0 Pizza Large"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7857,"template":"","meta":[],"product_cat":[229,230],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pierre \u00e0 Pizza Large - Grills et Saveurs<\/title>\n<meta name=\"description\" content=\"Pierre \u00e0 Pizza Large\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pierre \u00e0 Pizza Large - Grills et Saveurs\" \/>\n<meta property=\"og:description\" content=\"Pierre \u00e0 Pizza Large\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/\" \/>\n<meta property=\"og:site_name\" content=\"Grills et Saveurs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T09:49:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.36_Pizzastein.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/\",\"name\":\"Grills et Saveurs\",\"description\":\"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.36_Pizzastein.jpg\",\"contentUrl\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.36_Pizzastein.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/#webpage\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/\",\"name\":\"Pierre \u00e0 Pizza Large - Grills et Saveurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/#primaryimage\"},\"datePublished\":\"2022-05-23T12:25:42+00:00\",\"dateModified\":\"2024-04-08T09:49:36+00:00\",\"description\":\"Pierre \u00e0 Pizza Large\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop \/ Boutique\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pierre \u00e0 Pizza Large\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pierre \u00e0 Pizza Large - Grills et Saveurs","description":"Pierre \u00e0 Pizza Large","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/","og_locale":"fr_FR","og_type":"article","og_title":"Pierre \u00e0 Pizza Large - Grills et Saveurs","og_description":"Pierre \u00e0 Pizza Large","og_url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/","og_site_name":"Grills et Saveurs","article_modified_time":"2024-04-08T09:49:36+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.36_Pizzastein.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website","url":"https:\/\/www.grills-saveurs.ch\/fr\/","name":"Grills et Saveurs","description":"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.36_Pizzastein.jpg","contentUrl":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.36_Pizzastein.jpg","width":1000,"height":1000},{"@type":"WebPage","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/#webpage","url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/","name":"Pierre \u00e0 Pizza Large - Grills et Saveurs","isPartOf":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/#primaryimage"},"datePublished":"2022-05-23T12:25:42+00:00","dateModified":"2024-04-08T09:49:36+00:00","description":"Pierre \u00e0 Pizza Large","breadcrumb":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/pierre-a-pizza-large\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.grills-saveurs.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop \/ Boutique","item":"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Pierre \u00e0 Pizza Large"}]}]}},"_links":{"self":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product\/7855"}],"collection":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media\/7857"}],"wp:attachment":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media?parent=7855"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=7855"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=7855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}