{"id":7861,"date":"2022-05-23T14:27:17","date_gmt":"2022-05-23T12:27:17","guid":{"rendered":"https:\/\/www.grills-saveurs.ch\/fr\/?post_type=product&#038;p=7861"},"modified":"2024-04-08T11:49:35","modified_gmt":"2024-04-08T09:49:35","slug":"housse-de-protection-large","status":"publish","type":"product","link":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/","title":{"rendered":"Housse de protection Large"},"content":{"rendered":"<p>Une housse de pluie sp\u00e9cialement con\u00e7ue pour votre The Bastard, gr\u00e2ce \u00e0 la fermeture velcro qui assure une meilleures \u00e9tanch\u00e9it\u00e9. Fabriqu\u00e9e avec un rev\u00eatement PU de la plus haute qualit\u00e9 pour la protection contre le UV et avec des a\u00e9rations sp\u00e9cialement con\u00e7ues, votre The Bastard vous accompagnera chaque saison.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une housse de pluie sp\u00e9cialement con\u00e7ue pour votre The Bastard, gr\u00e2ce \u00e0 la fermeture velcro qui assure une meilleures \u00e9tanch\u00e9it\u00e9. Fabriqu\u00e9e avec un rev\u00eatement PU de la plus haute qualit\u00e9 pour la protection contre le UV et avec des a\u00e9rations sp\u00e9cialement con\u00e7ues, votre The Bastard vous accompagnera chaque saison.<\/p>\n","protected":false},"featured_media":7863,"template":"","meta":[],"product_cat":[229,230,254],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Housse de protection Large - Grills et Saveurs<\/title>\n<meta name=\"description\" content=\"Housse de protection Large\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Housse de protection Large - Grills et Saveurs\" \/>\n<meta property=\"og:description\" content=\"Housse de protection Large\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/\" \/>\n<meta property=\"og:site_name\" content=\"Grills et Saveurs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T09:49:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.01_Abdeckhaube_Large_Medium.png\" \/>\n\t<meta property=\"og:image:width\" content=\"428\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/\",\"name\":\"Grills et Saveurs\",\"description\":\"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.01_Abdeckhaube_Large_Medium.png\",\"contentUrl\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.01_Abdeckhaube_Large_Medium.png\",\"width\":428,\"height\":599},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/#webpage\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/\",\"name\":\"Housse de protection Large - Grills et Saveurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/#primaryimage\"},\"datePublished\":\"2022-05-23T12:27:17+00:00\",\"dateModified\":\"2024-04-08T09:49:35+00:00\",\"description\":\"Housse de protection Large\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop \/ Boutique\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Housse de protection Large\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Housse de protection Large - Grills et Saveurs","description":"Housse de protection Large","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/","og_locale":"fr_FR","og_type":"article","og_title":"Housse de protection Large - Grills et Saveurs","og_description":"Housse de protection Large","og_url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/","og_site_name":"Grills et Saveurs","article_modified_time":"2024-04-08T09:49:35+00:00","og_image":[{"width":428,"height":599,"url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.01_Abdeckhaube_Large_Medium.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website","url":"https:\/\/www.grills-saveurs.ch\/fr\/","name":"Grills et Saveurs","description":"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.01_Abdeckhaube_Large_Medium.png","contentUrl":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2022\/05\/2180.01_Abdeckhaube_Large_Medium.png","width":428,"height":599},{"@type":"WebPage","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/#webpage","url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/","name":"Housse de protection Large - Grills et Saveurs","isPartOf":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/#primaryimage"},"datePublished":"2022-05-23T12:27:17+00:00","dateModified":"2024-04-08T09:49:35+00:00","description":"Housse de protection Large","breadcrumb":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/housse-de-protection-large\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.grills-saveurs.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop \/ Boutique","item":"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Housse de protection Large"}]}]}},"_links":{"self":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product\/7861"}],"collection":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media\/7863"}],"wp:attachment":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media?parent=7861"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=7861"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=7861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}