{"id":8459,"date":"2023-04-21T17:26:03","date_gmt":"2023-04-21T15:26:03","guid":{"rendered":"https:\/\/www.grills-saveurs.ch\/fr\/?post_type=product&#038;p=8459"},"modified":"2024-04-08T17:06:18","modified_gmt":"2024-04-08T15:06:18","slug":"thermometre-infrarouge","status":"publish","type":"product","link":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/","title":{"rendered":"Thermom\u00e8tre infrarouge"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>R\u00e9f. 48651012 \/ 3380.13<\/p>\n","protected":false},"featured_media":8460,"template":"","meta":[],"product_cat":[236],"product_tag":[237],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Thermom\u00e8tre infrarouge - Grills et Saveurs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thermom\u00e8tre infrarouge - Grills et Saveurs\" \/>\n<meta property=\"og:description\" content=\"R\u00e9f. 48651012 \/ 3380.13\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/\" \/>\n<meta property=\"og:site_name\" content=\"Grills et Saveurs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T15:06:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2023\/04\/3380.13_Infrarotthermometer-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1740\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/\",\"name\":\"Grills et Saveurs\",\"description\":\"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2023\/04\/3380.13_Infrarotthermometer-scaled.jpg\",\"contentUrl\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2023\/04\/3380.13_Infrarotthermometer-scaled.jpg\",\"width\":1740,\"height\":2560},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/#webpage\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/\",\"name\":\"Thermom\u00e8tre infrarouge - Grills et Saveurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/#primaryimage\"},\"datePublished\":\"2023-04-21T15:26:03+00:00\",\"dateModified\":\"2024-04-08T15:06:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop \/ Boutique\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Thermom\u00e8tre infrarouge\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thermom\u00e8tre infrarouge - Grills et Saveurs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/","og_locale":"fr_FR","og_type":"article","og_title":"Thermom\u00e8tre infrarouge - Grills et Saveurs","og_description":"R\u00e9f. 48651012 \/ 3380.13","og_url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/","og_site_name":"Grills et Saveurs","article_modified_time":"2024-04-08T15:06:18+00:00","og_image":[{"width":1740,"height":2560,"url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2023\/04\/3380.13_Infrarotthermometer-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website","url":"https:\/\/www.grills-saveurs.ch\/fr\/","name":"Grills et Saveurs","description":"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2023\/04\/3380.13_Infrarotthermometer-scaled.jpg","contentUrl":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2023\/04\/3380.13_Infrarotthermometer-scaled.jpg","width":1740,"height":2560},{"@type":"WebPage","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/#webpage","url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/","name":"Thermom\u00e8tre infrarouge - Grills et Saveurs","isPartOf":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/#primaryimage"},"datePublished":"2023-04-21T15:26:03+00:00","dateModified":"2024-04-08T15:06:18+00:00","breadcrumb":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/thermometre-infrarouge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.grills-saveurs.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop \/ Boutique","item":"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Thermom\u00e8tre infrarouge"}]}]}},"_links":{"self":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product\/8459"}],"collection":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media\/8460"}],"wp:attachment":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media?parent=8459"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=8459"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=8459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}