{"id":9131,"date":"2024-04-08T09:24:11","date_gmt":"2024-04-08T07:24:11","guid":{"rendered":"https:\/\/www.grills-saveurs.ch\/fr\/?post_type=product&#038;p=9131"},"modified":"2024-04-08T09:24:12","modified_gmt":"2024-04-08T07:24:12","slug":"tete-de-rechange","status":"publish","type":"product","link":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/","title":{"rendered":"T\u00eate de rechange"},"content":{"rendered":"<p>Paquet de 2 t\u00eates de rechange pour les brosses \u00e0 barbecue 64014 et 64004.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paquet de 2 t\u00eates de rechange pour les brosses \u00e0 barbecue 64014 et 64004.<\/p>\n","protected":false},"featured_media":9133,"template":"","meta":[],"product_cat":[189,198,212],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T\u00eate de rechange - Grills et Saveurs<\/title>\n<meta name=\"description\" content=\"Paquet de 2 t\u00eates de rechange pour les brosses \u00e0 barbecue 64014 et 64004.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00eate de rechange - Grills et Saveurs\" \/>\n<meta property=\"og:description\" content=\"Paquet de 2 t\u00eates de rechange pour les brosses \u00e0 barbecue 64014 et 64004.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/\" \/>\n<meta property=\"og:site_name\" content=\"Grills et Saveurs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T07:24:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/03\/accessory_64015-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/\",\"name\":\"Grills et Saveurs\",\"description\":\"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/03\/accessory_64015-12.jpg\",\"contentUrl\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/03\/accessory_64015-12.jpg\",\"width\":600,\"height\":600},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/#webpage\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/\",\"name\":\"T\u00eate de rechange - Grills et Saveurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/#primaryimage\"},\"datePublished\":\"2024-04-08T07:24:11+00:00\",\"dateModified\":\"2024-04-08T07:24:12+00:00\",\"description\":\"Paquet de 2 t\u00eates de rechange pour les brosses \u00e0 barbecue 64014 et 64004.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop \/ Boutique\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T\u00eate de rechange\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00eate de rechange - Grills et Saveurs","description":"Paquet de 2 t\u00eates de rechange pour les brosses \u00e0 barbecue 64014 et 64004.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/","og_locale":"fr_FR","og_type":"article","og_title":"T\u00eate de rechange - Grills et Saveurs","og_description":"Paquet de 2 t\u00eates de rechange pour les brosses \u00e0 barbecue 64014 et 64004.","og_url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/","og_site_name":"Grills et Saveurs","article_modified_time":"2024-04-08T07:24:12+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/03\/accessory_64015-12.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website","url":"https:\/\/www.grills-saveurs.ch\/fr\/","name":"Grills et Saveurs","description":"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/03\/accessory_64015-12.jpg","contentUrl":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/03\/accessory_64015-12.jpg","width":600,"height":600},{"@type":"WebPage","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/#webpage","url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/","name":"T\u00eate de rechange - Grills et Saveurs","isPartOf":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/#primaryimage"},"datePublished":"2024-04-08T07:24:11+00:00","dateModified":"2024-04-08T07:24:12+00:00","description":"Paquet de 2 t\u00eates de rechange pour les brosses \u00e0 barbecue 64014 et 64004.","breadcrumb":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-rechange\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.grills-saveurs.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop \/ Boutique","item":"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"T\u00eate de rechange"}]}]}},"_links":{"self":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product\/9131"}],"collection":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media\/9133"}],"wp:attachment":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media?parent=9131"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=9131"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=9131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}