{"id":9313,"date":"2024-04-08T09:24:21","date_gmt":"2024-04-08T07:24:21","guid":{"rendered":"https:\/\/www.grills-saveurs.ch\/fr\/?post_type=product&#038;p=9313"},"modified":"2024-04-08T09:24:22","modified_gmt":"2024-04-08T07:24:22","slug":"tete-de-remplacement-pour-eponge-metallique","status":"publish","type":"product","link":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/","title":{"rendered":"T\u00eate de remplacement pour \u00e9ponge m\u00e9tallique"},"content":{"rendered":"<p>Sp\u00e9cialement con\u00e7u pour l&rsquo;\u00e9ponge m\u00e9tallique pour plancha. Pack de deux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>6210<\/p>\n","protected":false},"featured_media":9314,"template":"","meta":[],"product_cat":[167,122],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T\u00eate de remplacement pour \u00e9ponge m\u00e9tallique - Grills et Saveurs<\/title>\n<meta name=\"description\" content=\"Sp\u00e9cialement con\u00e7u pour l&#039;\u00e9ponge m\u00e9tallique pour plancha. Pack de deux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00eate de remplacement pour \u00e9ponge m\u00e9tallique - Grills et Saveurs\" \/>\n<meta property=\"og:description\" content=\"Sp\u00e9cialement con\u00e7u pour l&#039;\u00e9ponge m\u00e9tallique pour plancha. Pack de deux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/\" \/>\n<meta property=\"og:site_name\" content=\"Grills et Saveurs\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T07:24:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/04\/6210A.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/\",\"name\":\"Grills et Saveurs\",\"description\":\"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/04\/6210A.jpg\",\"contentUrl\":\"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/04\/6210A.jpg\",\"width\":800,\"height\":800},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/#webpage\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/\",\"name\":\"T\u00eate de remplacement pour \u00e9ponge m\u00e9tallique - Grills et Saveurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/#primaryimage\"},\"datePublished\":\"2024-04-08T07:24:21+00:00\",\"dateModified\":\"2024-04-08T07:24:22+00:00\",\"description\":\"Sp\u00e9cialement con\u00e7u pour l'\u00e9ponge m\u00e9tallique pour plancha. Pack de deux.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop \/ Boutique\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T\u00eate de remplacement pour \u00e9ponge m\u00e9tallique\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00eate de remplacement pour \u00e9ponge m\u00e9tallique - Grills et Saveurs","description":"Sp\u00e9cialement con\u00e7u pour l'\u00e9ponge m\u00e9tallique pour plancha. Pack de deux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/","og_locale":"fr_FR","og_type":"article","og_title":"T\u00eate de remplacement pour \u00e9ponge m\u00e9tallique - Grills et Saveurs","og_description":"Sp\u00e9cialement con\u00e7u pour l'\u00e9ponge m\u00e9tallique pour plancha. Pack de deux.","og_url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/","og_site_name":"Grills et Saveurs","article_modified_time":"2024-04-08T07:24:22+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/04\/6210A.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website","url":"https:\/\/www.grills-saveurs.ch\/fr\/","name":"Grills et Saveurs","description":"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/04\/6210A.jpg","contentUrl":"https:\/\/www.grills-saveurs.ch\/fr\/wp-content\/uploads\/2024\/04\/6210A.jpg","width":800,"height":800},{"@type":"WebPage","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/#webpage","url":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/","name":"T\u00eate de remplacement pour \u00e9ponge m\u00e9tallique - Grills et Saveurs","isPartOf":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/#primaryimage"},"datePublished":"2024-04-08T07:24:21+00:00","dateModified":"2024-04-08T07:24:22+00:00","description":"Sp\u00e9cialement con\u00e7u pour l'\u00e9ponge m\u00e9tallique pour plancha. Pack de deux.","breadcrumb":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grills-saveurs.ch\/fr\/produit\/tete-de-remplacement-pour-eponge-metallique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.grills-saveurs.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop \/ Boutique","item":"https:\/\/www.grills-saveurs.ch\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"T\u00eate de remplacement pour \u00e9ponge m\u00e9tallique"}]}]}},"_links":{"self":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product\/9313"}],"collection":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media\/9314"}],"wp:attachment":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/media?parent=9313"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=9313"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=9313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}