{"id":148,"count":0,"description":"","link":"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/","name":"Q \u00e0 gaz","slug":"q-a-gaz","taxonomy":"product_cat","parent":67,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Q \u00e0 gaz - Grills et Saveurs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Q \u00e0 gaz - Grills et Saveurs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/\" \/>\n<meta property=\"og:site_name\" content=\"Grills et Saveurs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/\",\"name\":\"Grills et Saveurs\",\"description\":\"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/#webpage\",\"url\":\"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/\",\"name\":\"Q \u00e0 gaz - Grills et Saveurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barbecues Weber\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barbecues \u00e0 gaz\",\"item\":\"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Q \u00e0 gaz\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Q \u00e0 gaz - Grills et Saveurs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/","og_locale":"fr_FR","og_type":"article","og_title":"Q \u00e0 gaz - Grills et Saveurs","og_url":"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/","og_site_name":"Grills et Saveurs","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website","url":"https:\/\/www.grills-saveurs.ch\/fr\/","name":"Grills et Saveurs","description":"Barbecues, Grills, Planchas, Chemin\u00e9es jardin - Lausanne, Suisse Romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grills-saveurs.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"CollectionPage","@id":"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/#webpage","url":"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/","name":"Q \u00e0 gaz - Grills et Saveurs","isPartOf":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/q-a-gaz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.grills-saveurs.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Barbecues Weber","item":"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/"},{"@type":"ListItem","position":3,"name":"Barbecues \u00e0 gaz","item":"https:\/\/www.grills-saveurs.ch\/fr\/product-category\/barbecues-weber\/barbecues-a-gaz\/"},{"@type":"ListItem","position":4,"name":"Q \u00e0 gaz"}]}]}},"_links":{"self":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat\/148"}],"collection":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product_cat\/67"}],"wp:post_type":[{"href":"https:\/\/www.grills-saveurs.ch\/fr\/wp-json\/wp\/v2\/product?product_cat=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}